{"id":34899,"date":"2021-01-28T13:45:27","date_gmt":"2021-01-28T13:45:27","guid":{"rendered":"https:\/\/travel-network.co\/recensioni-e-notizie-su-travel-network\/"},"modified":"2023-04-12T14:43:44","modified_gmt":"2023-04-12T14:43:44","slug":"recensioni-e-notizie-su-travel-network","status":"publish","type":"page","link":"https:\/\/travel-network.co\/it\/","title":{"rendered":"Recensioni e notizie su Travel Network"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center\">Recensioni di viaggio + Ultime notizie<\/h2>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Benvenuti nel nostro sito di viaggi, dove scriviamo le notizie di viaggio pi\u00f9 interessanti e recensiamo gli hotel e i ristoranti che abbiamo visitato durante i nostri viaggi. In passato abbiamo soggiornato in molti ostelli e molte di queste strutture hanno cambiato nome diverse volte e pi\u00f9 di qualcuna non esiste pi\u00f9. Cercheremo di coprire pi\u00f9 contenuti relativi alla Street Art, che \u00e8 uno degli elementi che preferiamo trovare nei nostri viaggi in giro per il mondo.  <\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<ul class=\"wp-block-latest-posts__list is-grid columns-2 has-dates wp-block-latest-posts has-medium-font-size\"><li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2015\/04\/Hilton-Berlin-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2015\/04\/Hilton-Berlin-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2015\/04\/Hilton-Berlin-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2015\/04\/Hilton-Berlin-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2015\/04\/Hilton-Berlin-65x65.jpg 65w, https:\/\/travel-network.co\/wp-content\/uploads\/2015\/04\/Hilton-Berlin-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/recensione-hilton-berlino\/\">Recensione Hilton Berlino<\/a><time datetime=\"2025-06-04T11:00:38+00:00\" class=\"wp-block-latest-posts__post-date\">Giugno 4, 2025<\/time><div class=\"wp-block-latest-posts__post-excerpt\">L&#8217;Hilton Berlin si trova di fronte a una delle piazze storiche pi\u00f9 belle della Germania, il Gendarmenmarkt, nel quartiere di Mitte. L&#8217;hotel \u00e8 una posizione perfetta per chi si trova in citt\u00e0 per lavoro o per partecipare a un evento. L&#8217;hotel dispone inoltre di un numero ragionevole di strutture per una posizione centrale, con un Health Club di 800 m\u00b2 con centro fitness 24 ore su 24, sauna e piscina coperta. Al momento del check-in\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/recensione-hilton-berlino\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Recensione Hilton Berlino<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2025\/05\/20250505_125506-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Cambrils\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2025\/05\/20250505_125506-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2025\/05\/20250505_125506-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2025\/05\/20250505_125506-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/recensione-del-cambrils-park-resort\/\">Recensione del Cambrils Park Resort<\/a><time datetime=\"2025-05-12T10:44:35+00:00\" class=\"wp-block-latest-posts__post-date\">Maggio 12, 2025<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Innanzitutto \u00e8 una posizione meravigliosa sulla costa della Spagna e le molteplici opzioni per le piscine erano incredibili. Gli scivoli non erano adatti a persone pi\u00f9 grandi o pi\u00f9 alte, ma i bambini sembravano divertirsi molto. Il campeggio dispone di un \u201cottima panetteria e di un supermercato in loco con prezzi ragionevoli. C\u201d \u00e8 un parco giochi decente vicino alla piscina di sabbia con il Faro e si possono acquistare degli ottimi mocktail e gelati.\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/recensione-del-cambrils-park-resort\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Recensione del Cambrils Park Resort<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2024\/10\/20240828_064951-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2024\/10\/20240828_064951-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2024\/10\/20240828_064951-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2024\/10\/20240828_064951-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/punture-di-cimici-dei-letti-al-london-marriott-hotel-canary-wharf\/\">Punture di cimici dei letti del London Marriott Hotel Canary Wharf<\/a><time datetime=\"2024-10-03T14:20:14+00:00\" class=\"wp-block-latest-posts__post-date\">Ottobre 3, 2024<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Per questo motivo avevo grandi speranze su questa struttura ad agosto, essendoci passato davanti centinaia di volte quando vivevo a Londra o visitavo Canary Wharf. L&#8217;hotel si trovava vicino all&#8217;aeroporto di London City e quindi era facile da raggiungere, dato che sono arrivato in tarda serata e non volevo dover attraversare Londra con i miei bagagli. Quando ho fatto il check-in, il personale del Marriott \u00e8 stato gentile e accogliente, il che \u00e8 sempre un\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/punture-di-cimici-dei-letti-al-london-marriott-hotel-canary-wharf\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Punture di cimici dei letti del London Marriott Hotel Canary Wharf<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/11\/20231014_100909-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"STRAAT Museum for Street Art, NDSM, Amsterdam\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/11\/20231014_100909-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/11\/20231014_100909-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/11\/20231014_100909-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/museo-straat-per-larte-di-strada\/\">Museo STRAAT per l&#8217;arte di strada<\/a><time datetime=\"2023-11-14T10:28:43+00:00\" class=\"wp-block-latest-posts__post-date\">Novembre 14, 2023<\/time><div class=\"wp-block-latest-posts__post-excerpt\">L&#8217;ex magazzino di 8000 m2 situato al molo di NDSM ospita STRAAT, un museo di livello mondiale per la street art e i graffiti con oltre 180 opere d&#8217;arte esposte da almeno 170 artisti di tutto il mondo. L&#8217;area circostante l&#8217;NDSM \u00e8 caratterizzata dai muri dell&#8217;NDSM, un&#8217;area legale per gli artisti di strada di tutto il mondo che possono creare 24 ore su 24, 7 giorni su 7. STRAAT \u00e8 curato da un team di\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/museo-straat-per-larte-di-strada\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Museo STRAAT per l&#8217;arte di strada<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/05\/20230525_175459-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Holiday Inn Lisbon\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/05\/20230525_175459-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/05\/20230525_175459-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/05\/20230525_175459-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/recensione-holiday-inn-lisbon-continental\/\">Recensione Holiday Inn Lisbon Continental<\/a><time datetime=\"2023-05-25T15:31:21+00:00\" class=\"wp-block-latest-posts__post-date\">Maggio 25, 2023<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Se state prenotando un viaggio a Lisbona, sappiate che in realt\u00e0 ci sono 7 sedi di Holiday Inn in tutta la citt\u00e0. Il luogo in cui ho soggiornato si chiama ufficialmente Holiday Inn Lisbon &#8211; Continental, ma Campo Pequeno \u00e8 uno dei luoghi pi\u00f9 popolari per chi fa brevi scali grazie alla sua vicinanza all&#8217;aeroporto Humberto Delgado. \u00c8 a soli 15-20 minuti di taxi dall&#8217;aeroporto e abbastanza lontano dalla nostra citt\u00e0 da evitare gran parte\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/recensione-holiday-inn-lisbon-continental\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Recensione Holiday Inn Lisbon Continental<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/03\/statue-of-liberty-pedestal-tour-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Statue of Liberty pedestal base tour\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/03\/statue-of-liberty-pedestal-tour-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/03\/statue-of-liberty-pedestal-tour-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/03\/statue-of-liberty-pedestal-tour-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/crociere-nella-citta-della-statua-della-liberta\/\">Crociere nella citt\u00e0 della Statua della Libert\u00e0<\/a><time datetime=\"2023-03-11T20:06:51+00:00\" class=\"wp-block-latest-posts__post-date\">Marzo 11, 2023<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Vi consiglio di prenotare un tour al mattino presto, se potete, perch\u00e9 molte persone rimangono sull&#8217;isola per diverse ore&#8230; Io avevo un biglietto per le 9 del mattino, il che significava aspettare in una fila enorme per i controlli di sicurezza in stile aeroporto. L&#8217;intero processo \u00e8 durato 45 minuti, poich\u00e9 sono arrivato alle 8.45 e sono stato imbarcato con centinaia di altre persone. Ricordate che Statue City Cruises \u00e8 l&#8217;UNICO fornitore autorizzato a fornire\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/crociere-nella-citta-della-statua-della-liberta\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Crociere nella citt\u00e0 della Statua della Libert\u00e0<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/01\/hilton-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Hampton by Hilton Belfast City Centre\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2023\/01\/hilton-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/01\/hilton-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2023\/01\/hilton-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/recensione-di-hampton-by-hilton-belfast-city-centre\/\">Recensione di Hampton by Hilton Belfast City Centre<\/a><time datetime=\"2022-12-28T12:34:20+00:00\" class=\"wp-block-latest-posts__post-date\">Dicembre 28, 2022<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Abbiamo scelto l&#8217;hotel Hampton by Hilton Belfast come luogo di fuga per il nostro regalo di Natale, e l&#8217;ho scelto anche per la sua vicinanza alla stazione ferroviaria di Great Victoria Street. Ho dimenticato di controllare che il treno Enterprise da Dublino si fermi alla stazione di Lanyon Place, ma era comunque a soli 20 minuti a piedi o a circa 7 sterline con un Uber, ma era molto pi\u00f9 vicino dell&#8217;Holiday Inn Express in\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/recensione-di-hampton-by-hilton-belfast-city-centre\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Recensione di Hampton by Hilton Belfast City Centre<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2021\/11\/yha-new-zealand-closes-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Guest bookings up to and including these dates remain in place and hostels will be operating as usual until then. We are cancelling and fully refunding all bookings for stays after the closure date over the coming weeks.\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2021\/11\/yha-new-zealand-closes-150x150.png 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/11\/yha-new-zealand-closes-100x100.png 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/11\/yha-new-zealand-closes-300x300.png 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/11\/yha-new-zealand-closes-96x96.png 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/chiude-gli-ostelli-gestiti-da-yha-nuova-zelanda\/\">Chiude gli ostelli gestiti da YHA Nuova Zelanda<\/a><time datetime=\"2021-11-29T05:05:21+00:00\" class=\"wp-block-latest-posts__post-date\">Novembre 29, 2021<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Dopo oltre 89 anni di attivit\u00e0, il Coronavirus ha colpito un altro marchio globale di viaggi: 11 ostelli gestiti dalla YHA Nuova Zelanda chiuderanno il 15 dicembre 2021, mentre le prenotazioni nazionali sono aumentate significativamente, non \u00e8 stato sufficiente a compensare il calo dei viaggiatori internazionali. Le prenotazioni degli ospiti YHA fino a queste date rimangono valide e gli ostelli funzioneranno come al solito fino ad allora. YHA sta cancellando e rimborsando completamente tutte le\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/chiude-gli-ostelli-gestiti-da-yha-nuova-zelanda\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Chiude gli ostelli gestiti da YHA Nuova Zelanda<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2021\/01\/webversion-dsc2746-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2021\/01\/webversion-dsc2746-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/01\/webversion-dsc2746-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/01\/webversion-dsc2746-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/01\/webversion-dsc2746-640x640.jpg 640w, https:\/\/travel-network.co\/wp-content\/uploads\/2021\/01\/webversion-dsc2746-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/schiphol-vieta-tutti-i-voli-in-sud-america-regno-unito-e-sud-africa\/\">Schiphol vieta tutti i voli in Sud America, Regno Unito e Sud Africa<\/a><time datetime=\"2021-01-20T14:44:00+00:00\" class=\"wp-block-latest-posts__post-date\">Gennaio 20, 2021<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Il governo olandese ha annunciato mercoled\u00ec 20 novembre che ci sar\u00e0 un divieto di volo per il traffico aereo da tutto il Sud America, il Regno Unito e il Sud Africa dal 23 gennaio. Questo per rallentare la diffusione dei nuovi ceppi di Coronavirus dal Regno Unito (variante B.1.1.7), Brasile (mutazione E484K) e Sud Africa (variante B.1.351). Questo \u00e8 il primo vero passo proattivo fatto dal governo olandese per rallentare la diffusione del Coronavirus dai\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/schiphol-vieta-tutti-i-voli-in-sud-america-regno-unito-e-sud-africa\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Schiphol vieta tutti i voli in Sud America, Regno Unito e Sud Africa<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/The-Roosevelt-Hotel-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"The Roosevelt Hotel\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/The-Roosevelt-Hotel-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/The-Roosevelt-Hotel-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/The-Roosevelt-Hotel-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/The-Roosevelt-Hotel-640x640.jpg 640w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/The-Roosevelt-Hotel-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/lhotel-roosevelt-chiude\/\">L&#8217;hotel Roosevelt chiude<\/a><time datetime=\"2020-10-15T20:35:22+00:00\" class=\"wp-block-latest-posts__post-date\">Ottobre 15, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">In quella che potrebbe essere una delle chiusure di pi\u00f9 alto profilo a causa del Coronavirus, il punto di riferimento di Manhattan ha chiuso dopo 96 anni. L&#8217;hotel di New York \u00e8 stato aperto il 22 settembre 1924 dal politico, albergatore e avvocato americano Frank A Dudley ed \u00e8 stato nominato in onore del residente Theodore Roosevelt. L&#8217;hotel \u00e8 uno degli alberghi pi\u00f9 grandi di NYC con 1.025 camere con 33 suite su 19 piani.\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/lhotel-roosevelt-chiude\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: L&#8217;hotel Roosevelt chiude<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/Alitalia-becomes-ITA-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/Alitalia-becomes-ITA-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/Alitalia-becomes-ITA-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/Alitalia-becomes-ITA-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/Alitalia-becomes-ITA-640x640.jpg 640w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/Alitalia-becomes-ITA-96x96.jpg 96w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/alitalia-sostituito-da-ita\/\">Alitalia sostituito da ITA<\/a><time datetime=\"2020-10-15T19:56:55+00:00\" class=\"wp-block-latest-posts__post-date\">Ottobre 15, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Il vettore nazionale Alitalia, fortemente indebitato e fallito, \u00e8 finalmente destinato ad essere sostituito, con il nuovo ITA di propriet\u00e0 dello Stato. ITA sta per Italia Trasporto Aereo e potrebbe essere molto pi\u00f9 facile per i turisti soggiornare. Un ostacolo pi\u00f9 grande per la nuova compagnia aerea \u00e8 la possibilit\u00e0 di essere trovata dai viaggiatori su Google, visto che attualmente si trova ad affrontare la concorrenza del software Matrix di Google. Anche in Olanda ITA\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/alitalia-sostituito-da-ita\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Alitalia sostituito da ITA<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/amsterdam-to-paris-train-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Amsterdam to Paris Train\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/amsterdam-to-paris-train-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/amsterdam-to-paris-train-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/amsterdam-to-paris-train-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/amsterdam-to-paris-train-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/10\/amsterdam-to-paris-train-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/treno-da-amsterdam-a-parigi-nord\/\">Treno da Amsterdam a Parigi Nord<\/a><time datetime=\"2020-10-05T09:06:18+00:00\" class=\"wp-block-latest-posts__post-date\">Ottobre 5, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Mentre il servizio ferroviario internazionale da e per i Paesi Bassi \u00e8 in gran parte ripreso dopo la chiusura delle frontiere. Il personale ferroviario di Thalys e della NS chiede di evitare la folla e di mantenere la massima distanza possibile sul treno. Le maschere facciali rimangono obbligatorie per tutti i passeggeri del treno. Il personale di stazione chiede inoltre esplicitamente di indossare una maschera facciale dal momento in cui si entra in stazione, anche\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/treno-da-amsterdam-a-parigi-nord\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Treno da Amsterdam a Parigi Nord<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/disney-parks-cuts-staff-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"A statement from Josh D\u2019Amaro, Chairman, Disney Parks, Experiences and Products:\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/disney-parks-cuts-staff-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/disney-parks-cuts-staff-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/disney-parks-cuts-staff-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/disney-parks-cuts-staff-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/disney-parks-cuts-staff-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/disney-parks-taglia-28-000-dipendenti\/\">Disney Parks taglia 28.000 dipendenti<\/a><time datetime=\"2020-09-29T23:01:35+00:00\" class=\"wp-block-latest-posts__post-date\">Settembre 29, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Oggi Josh D&#8217;Amaro, presidente di Disney Parchi, Esperienze e Prodotti, ha annunciato il vero impatto del Coronavirus sui parchi Disney. Disney licenzier\u00e0 circa 28.000 dipendenti su 100.000 dopo aver inizialmente licenziato un gran numero di loro dipendenti che non erano necessari il 19 aprile 2020. Disney Parchi Disney ha avuto un impatto enorme per i suoi resort in tutti gli Stati Uniti, ma anche a livello globale con i loro profitti in calo del 91%\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/disney-parks-taglia-28-000-dipendenti\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Disney Parks taglia 28.000 dipendenti<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"chicago o hare international airport\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-scaled-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-1472x1472.jpg 1472w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-1104x1104.jpg 1104w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-912x912.jpg 912w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/chicago-ohare-international-airport-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/united-airlines-chiude-le-basi-di-hong-kong-tokyo-e-francoforte\/\">United Airlines chiude le basi di Hong Kong, Tokyo e Francoforte<\/a><time datetime=\"2020-09-26T21:31:00+00:00\" class=\"wp-block-latest-posts__post-date\">Settembre 26, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Uno dei maggiori impatti del Coronavirus \u00e8 stato quello di gruppi di compagnie aeree e alberghieri in tutto il mondo. Cos\u00ec CNBC ha annunciato nel giugno 2020 che United Airlines aveva pianificato di chiudere 3 delle 4 basi di assistenti di volo internazionali, dato che la loro domanda di viaggi internazionali era crollata. C&#8217;erano 840 assistenti di volo che lavorano in queste 3 sedi e il memorandum diceva che c&#8217;era la possibilit\u00e0 di trasferirsi in\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/united-airlines-chiude-le-basi-di-hong-kong-tokyo-e-francoforte\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: United Airlines chiude le basi di Hong Kong, Tokyo e Francoforte<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Whitbread to cut 6,000 jobs as hotel demand slumps\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-scaled-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-1472x1472.jpg 1472w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-1104x1104.jpg 1104w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-912x912.jpg 912w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/premier-inn-team-members-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/premier-inn-brewers-fayre-proprietario-whitbread-cut-18-dei-dipendenti\/\">Premier Inn &#038; Brewers Fayre Proprietario Whitbread Cut 18% dei dipendenti<\/a><time datetime=\"2020-09-23T19:50:00+00:00\" class=\"wp-block-latest-posts__post-date\">Settembre 23, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Whitbread \u00e8 uno dei pi\u00f9 grandi operatori di hotel e ristoranti del Regno Unito con oltre 35.000 dipendenti che lavorano con i loro marchi Premier Inn, Brewers Fayer, Beefeater, Cookhouse &amp; Pub, Bar + Block Steakhouse, Timo e TableTable. Il loro team serve circa 5 milioni di clienti in tutto il Regno Unito ogni mese, quindi il Coronavirus ha avuto un impatto enorme sulla loro attivit\u00e0, dato che la domanda di hotel \u00e8 caduta da\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/premier-inn-brewers-fayre-proprietario-whitbread-cut-18-dei-dipendenti\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Premier Inn &#038; Brewers Fayre Proprietario Whitbread Cut 18% dei dipendenti<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"KLM requires passengers to wear face masks\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-600x600.jpg 600w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-1024x1024.jpg 1024w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-768x768.jpg 768w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-1104x1104.jpg 1104w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-912x912.jpg 912w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask-470x470.jpg 470w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/09\/klm-requires-face-mask.jpg 1200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/klm-richiede-maschere-da-indossare\/\">KLM richiede maschere da indossare<\/a><time datetime=\"2020-09-16T12:45:10+00:00\" class=\"wp-block-latest-posts__post-date\">Settembre 16, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">KLM ha fatto il passo giusto per proteggere i propri passeggeri e rallentare la diffusione del Coronavirus con l&#8217;annuncio che richiede a tutti i passeggeri e all&#8217;equipaggio di indossare una protezione per il viso. KLM si \u00e8 allineata con i partner dell&#8217;alleanza SkyTeam, come Delta Air Lines, che richiede a tutti i passeggeri di et\u00e0 superiore ai 2 anni di indossare una protezione per il viso a bordo di un volo. KLM non \u00e8 cos\u00ec\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/klm-richiede-maschere-da-indossare\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: KLM richiede maschere da indossare<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/american-airlines-suspends-services-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"American Airlines Suspends Service to 15 Markets in October as CARES Act Service Commitment Expires\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/american-airlines-suspends-services-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/american-airlines-suspends-services-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/american-airlines-suspends-services-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/american-airlines-suspends-services-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/american-airlines-suspends-services-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/american-airlines-ha-tagliato-il-30-dei-posti-di-lavoro\/\">American Airlines ha tagliato il 30% dei posti di lavoro<\/a><time datetime=\"2020-08-25T16:06:37+00:00\" class=\"wp-block-latest-posts__post-date\">Agosto 25, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">American Airlines ha annunciato che licenzier\u00e0 19.000 dei suoi 140.000 lavoratori in ottobre come i 25 miliardi di dollari di aiuti federali ricevuti dal Payroll Support Program (PSP) creato nell&#8217;ambito del Coronavirus Aid, Relief, and Economic Security Act (CARES Act). All&#8217;inizio di quest&#8217;anno American Airlines ha ricevuto 5,8 miliardi di dollari di sostegno al libro paga, un prestito a basso tasso d&#8217;interesse di 1,7 miliardi di dollari e aveva previsto di richiedere un ulteriore prestito\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/american-airlines-ha-tagliato-il-30-dei-posti-di-lavoro\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: American Airlines ha tagliato il 30% dei posti di lavoro<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/Qantas-international-flights-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"QANTAS GROUP FY20 FINANCIAL RESULTS\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/Qantas-international-flights-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/Qantas-international-flights-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/Qantas-international-flights-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/Qantas-international-flights-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/Qantas-international-flights-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/nessun-volo-internazionale-qantas-fino-a-luglio-2021\/\">Nessun volo internazionale Qantas fino a luglio 2021<\/a><time datetime=\"2020-08-20T09:50:45+00:00\" class=\"wp-block-latest-posts__post-date\">Agosto 20, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">A riprova di quanto il Coronavirus abbia avuto un impatto sui viaggi internazionali, Qantas, la pi\u00f9 grande compagnia aerea australiana, ha annunciato di non aver previsto voli internazionali fino al luglio 2021. La notizia \u00e8 arrivata come parte dei risultati del FY202020 di Qantas Group e ha mandato un po&#8217; di shock tra gli espatriati australiani in tutto il mondo. Alan Joyce, CEO del Qantas Group, ha dichiarato in una dichiarazione che la seconda met\u00e0\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/nessun-volo-internazionale-qantas-fino-a-luglio-2021\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Nessun volo internazionale Qantas fino a luglio 2021<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/easy-jet-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"EasyJet confirms closure of Stansted, Newcastle and Southend airport bases\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/easy-jet-2-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/easy-jet-2-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/easy-jet-2-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/easy-jet-2-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/easy-jet-2-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/easyjet-chiude-stansted-newcastle-e-southend\/\">EasyJet chiude Stansted, Newcastle e Southend<\/a><time datetime=\"2020-08-18T14:52:19+00:00\" class=\"wp-block-latest-posts__post-date\">Agosto 18, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">EasyJet ha confermato la notizia che s\u00ec, interromper\u00e0 3 delle sue basi nel Regno Unito di Stansted, Southend &amp; Newcastle, dato che il Coronavirus continua ad avere un impatto sulla domanda di viaggi. Il trasferimento avr\u00e0 un impatto su circa 670 posti di lavoro ed entrer\u00e0 in vigore a partire dal 1\u00b0 settembre 2020. I passeggeri in partenza da Londra avranno ancora opzioni da Londra Luton &amp; Londra Gatwick, ma i passeggeri di Newcastle dovranno\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/easyjet-chiude-stansted-newcastle-e-southend\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: EasyJet chiude Stansted, Newcastle e Southend<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Ostelli di New York\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-65x65.jpg 65w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-1104x1104.jpg 1104w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-912x912.jpg 912w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/08\/IMG_5170-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/ostelli-di-new-york\/\">Ostelli di New York<\/a><time datetime=\"2020-08-12T20:39:52+00:00\" class=\"wp-block-latest-posts__post-date\">Agosto 12, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">New York City \u00e8 una delle migliori destinazioni turistiche del mondo, \u00e8 la citt\u00e0 che veramente non dorme mai. La prima cosa che dovete capire che questa pagina si concentrer\u00e0 su New York City che si trova nello stato di New York, sulla costa orientale degli Stati Uniti. La citt\u00e0 \u00e8 composta da 5 distretti di Manhattan, Queens, Brooklyn, The Bronx e anche Staten Island. Quando la maggior parte delle persone pensa di New York\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/ostelli-di-new-york\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Ostelli di New York<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Carnival Cruise Lines\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-65x65.jpg 65w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/carnival-cruise-lines-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/carnival-cruises-offre-agli-ospiti-bevande-gratuite\/\">Carnival Cruises offre agli ospiti bevande gratuite<\/a><time datetime=\"2020-03-10T23:06:57+00:00\" class=\"wp-block-latest-posts__post-date\">Marzo 10, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Yep che \u00e8 cos\u00ec gli ospiti hanno ricevuto lettere da Carnevale che se non annullano il loro programma di prenotazioni per partire da ora fino al 31 maggio 2020 riceveranno crediti a bordo per bevande, trattamenti termali ed escursioni. Il valore dei crediti dipende dalla durata della crociera 100 USD per cabina per crociere di 3-4 giorni 150 USD per cabina per crociere di 5 giorni 200 USD per cabina per crociere di oltre 6\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/carnival-cruises-offre-agli-ospiti-bevande-gratuite\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Carnival Cruises offre agli ospiti bevande gratuite<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"St Patrick&#039;s Day 2020 cancelled\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-65x65.jpg 65w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-912x912.jpg 912w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/st-patricks-day-festival-cancelled-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/parate-del-giorno-di-san-patrizio-cancellate-a-causa-di-coronavirus\/\">Parate del giorno di San Patrizio cancellate a causa di Coronavirus<\/a><time datetime=\"2020-03-10T22:46:37+00:00\" class=\"wp-block-latest-posts__post-date\">Marzo 10, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Sembra che le sfilate del Giorno di San Patrizio in tutta l&#8217;Irlanda del Nord e la Repubblica d&#8217;Irlanda non andranno avanti. Luned\u00ec 9 marzo 2020, il Taoiseach (PM irlandese) Leo Varadkar ha deciso, con il sostegno del consiglio e della direzione del St Patrick&#8217;s Festival, di annullare tutte le sfilate del Giorno di San Patrizio in Irlanda. Pi\u00f9 tardi, quel giorno, il belfast City Council decise di seguire il loro esempio e di cancellare la\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/parate-del-giorno-di-san-patrizio-cancellate-a-causa-di-coronavirus\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Parate del giorno di San Patrizio cancellate a causa di Coronavirus<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/qatar-airways-coronavirus-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Qatar Airways Launches New Policy to Provide Maximum Flexibility for Passengers\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/qatar-airways-coronavirus-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/qatar-airways-coronavirus-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/qatar-airways-coronavirus-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/qatar-airways-coronavirus-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/qatar-airways-offre-prenotazioni-flessibili-grazie-a-coronavirus\/\">Qatar Airways offre prenotazioni flessibili grazie a Coronavirus<\/a><time datetime=\"2020-03-09T01:16:47+00:00\" class=\"wp-block-latest-posts__post-date\">Marzo 9, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Qatar Airways ha lanciato una nuova politica commerciale per fornire ai clienti la massima flessibilit\u00e0 per soddisfare i loro piani di viaggio. Ai passeggeri che hanno prenotato o prenotato voli per viaggi fino al 30 giugno 2020 sar\u00e0 offerta la flessibilit\u00e0 di modificare gratuitamente i loro piani di viaggio modificando le date della prenotazione o scambiando il biglietto per un voucher di viaggio valido per un anno. Entrambe le modifiche si applicano fino a tre\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/qatar-airways-offre-prenotazioni-flessibili-grazie-a-coronavirus\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Qatar Airways offre prenotazioni flessibili grazie a Coronavirus<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"Royal Air Maroc\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-65x65.jpg 65w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-912x912.jpg 912w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-550x550.jpg 550w, https:\/\/travel-network.co\/wp-content\/uploads\/2020\/03\/royal-air-maroc-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/royal-air-maroc-coronavirus-aggiornamenti\/\">Royal Air Maroc Coronavirus aggiornamenti<\/a><time datetime=\"2020-03-09T00:41:12+00:00\" class=\"wp-block-latest-posts__post-date\">Marzo 9, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Marted\u00ec 6 marzo Royal Air Maroc ha implementato misure per rallentare la diffusione del Coronavirus (COVID19). Queste nuove misure sono restrizioni nazionali sono temporanee, ma si applicano a tutti i suoi voli. I clienti che hanno acquistato i biglietti prima del 31 marzo 2020 avranno la possibilit\u00e0 di: 1) Posticipare il viaggio fino al 31 maggio, gratuitamente fino a 72 ore prima dell&#8217;orario di partenza 2) Annullare il viaggio, gratuitamente, fino a 72 ore prima\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/royal-air-maroc-coronavirus-aggiornamenti\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Royal Air Maroc Coronavirus aggiornamenti<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/travel-network.co\/wp-content\/uploads\/2017\/08\/Ibis-Madrid-Alcobendas-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"max-width:150px;max-height:150px;\" srcset=\"https:\/\/travel-network.co\/wp-content\/uploads\/2017\/08\/Ibis-Madrid-Alcobendas-150x150.jpg 150w, https:\/\/travel-network.co\/wp-content\/uploads\/2017\/08\/Ibis-Madrid-Alcobendas-300x300.jpg 300w, https:\/\/travel-network.co\/wp-content\/uploads\/2017\/08\/Ibis-Madrid-Alcobendas-100x100.jpg 100w, https:\/\/travel-network.co\/wp-content\/uploads\/2017\/08\/Ibis-Madrid-Alcobendas-65x65.jpg 65w, https:\/\/travel-network.co\/wp-content\/uploads\/2017\/08\/Ibis-Madrid-Alcobendas-470x470.jpg 470w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/travel-network.co\/it\/recensione-ibis-madrid-alcobendas\/\">Recensione Ibis Madrid Alcobendas<\/a><time datetime=\"2020-03-07T01:59:46+00:00\" class=\"wp-block-latest-posts__post-date\">Marzo 7, 2020<\/time><div class=\"wp-block-latest-posts__post-excerpt\">Questo ibis Hotel Alcobendas a 2 stelle con 120 camere si trova proprio accanto a un parco industriale che andava bene, dato che avevamo bisogno di un hotel per la notte che fosse in una posizione vicino all&#8217;aeroporto che non fosse troppo costosa. Siamo stati qui nel giugno 2017, quindi \u00e8 stato un po&#8217; fastidioso perch\u00e9 l&#8217;aria condizionata nella stanza sembrava soffiare aria calda e fare strani rumori. Ma siccome avevamo un volo di prima\u2026 <a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/travel-network.co\/it\/recensione-ibis-madrid-alcobendas\/\" rel=\"noopener noreferrer\">Leggi tutto<span class=\"screen-reader-text\">: Recensione Ibis Madrid Alcobendas<\/span><\/a><\/div><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Recensioni di viaggio + Ultime notizie Benvenuti nel nostro sito di viaggi, dove scriviamo le notizie di viaggio pi\u00f9 interessanti [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-34899","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recensioni e notizie su Travel Network - Travel Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travel-network.co\/it\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recensioni e notizie su Travel Network - Travel Network\" \/>\n<meta property=\"og:description\" content=\"Recensioni di viaggio + Ultime notizie Benvenuti nel nostro sito di viaggi, dove scriviamo le notizie di viaggio pi\u00f9 interessanti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travel-network.co\/it\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Network\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/travel.au\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-12T14:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travel-network.co\/wp-content\/uploads\/2015\/03\/google-logo.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelnetworkau\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/\",\"url\":\"https:\\\/\\\/travel-network.co\\\/it\\\/\",\"name\":\"Recensioni e notizie su Travel Network - Travel Network\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#website\"},\"datePublished\":\"2021-01-28T13:45:27+00:00\",\"dateModified\":\"2023-04-12T14:43:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travel-network.co\\\/it\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travel-network.co\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recensioni e notizie su Travel Network\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/travel-network.co\\\/it\\\/\",\"name\":\"Travel Network\",\"description\":\"Travel advice, reviews, news and deals no matter if you are travelling by Land, Water or Air\",\"publisher\":{\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travel-network.co\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#organization\",\"name\":\"Travel Network\",\"url\":\"https:\\\/\\\/travel-network.co\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travel-network.co\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/google-logo.gif\",\"contentUrl\":\"https:\\\/\\\/travel-network.co\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/google-logo.gif\",\"width\":500,\"height\":500,\"caption\":\"Travel Network\"},\"image\":{\"@id\":\"https:\\\/\\\/travel-network.co\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/travel.au\",\"https:\\\/\\\/x.com\\\/travelnetworkau\",\"https:\\\/\\\/instagram.com\\\/travelnetworkau\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/3374753\",\"https:\\\/\\\/www.pinterest.com\\\/travelnetwork\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/TravelNetworkAUS\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recensioni e notizie su Travel Network - Travel Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travel-network.co\/it\/","og_locale":"it_IT","og_type":"article","og_title":"Recensioni e notizie su Travel Network - Travel Network","og_description":"Recensioni di viaggio + Ultime notizie Benvenuti nel nostro sito di viaggi, dove scriviamo le notizie di viaggio pi\u00f9 interessanti [&hellip;]","og_url":"https:\/\/travel-network.co\/it\/","og_site_name":"Travel Network","article_publisher":"http:\/\/facebook.com\/travel.au","article_modified_time":"2023-04-12T14:43:44+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/travel-network.co\/wp-content\/uploads\/2015\/03\/google-logo.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_site":"@travelnetworkau","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travel-network.co\/it\/","url":"https:\/\/travel-network.co\/it\/","name":"Recensioni e notizie su Travel Network - Travel Network","isPartOf":{"@id":"https:\/\/travel-network.co\/it\/#website"},"datePublished":"2021-01-28T13:45:27+00:00","dateModified":"2023-04-12T14:43:44+00:00","breadcrumb":{"@id":"https:\/\/travel-network.co\/it\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travel-network.co\/it\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/travel-network.co\/it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travel-network.co\/it\/"},{"@type":"ListItem","position":2,"name":"Recensioni e notizie su Travel Network"}]},{"@type":"WebSite","@id":"https:\/\/travel-network.co\/it\/#website","url":"https:\/\/travel-network.co\/it\/","name":"Travel Network","description":"Travel advice, reviews, news and deals no matter if you are travelling by Land, Water or Air","publisher":{"@id":"https:\/\/travel-network.co\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travel-network.co\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/travel-network.co\/it\/#organization","name":"Travel Network","url":"https:\/\/travel-network.co\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/travel-network.co\/it\/#\/schema\/logo\/image\/","url":"https:\/\/travel-network.co\/wp-content\/uploads\/2015\/03\/google-logo.gif","contentUrl":"https:\/\/travel-network.co\/wp-content\/uploads\/2015\/03\/google-logo.gif","width":500,"height":500,"caption":"Travel Network"},"image":{"@id":"https:\/\/travel-network.co\/it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/travel.au","https:\/\/x.com\/travelnetworkau","https:\/\/instagram.com\/travelnetworkau\/","https:\/\/www.linkedin.com\/company\/3374753","https:\/\/www.pinterest.com\/travelnetwork\/","http:\/\/www.youtube.com\/user\/TravelNetworkAUS"]}]}},"_links":{"self":[{"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/pages\/34899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/comments?post=34899"}],"version-history":[{"count":0,"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/pages\/34899\/revisions"}],"wp:attachment":[{"href":"https:\/\/travel-network.co\/it\/wp-json\/wp\/v2\/media?parent=34899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}